{"id":110,"date":"2017-08-18T16:28:45","date_gmt":"2017-08-18T16:28:45","guid":{"rendered":"http:\/\/palenquerobledal.com\/web\/?p=110"},"modified":"2021-11-04T03:12:44","modified_gmt":"2021-11-04T03:12:44","slug":"ceder-el-asiento-una-cuestion-de-educacion","status":"publish","type":"post","link":"https:\/\/palenquerobledal.com\/web\/2017\/08\/18\/ceder-el-asiento-una-cuestion-de-educacion\/","title":{"rendered":"Ceder el asiento, una cuesti\u00f3n de educaci\u00f3n."},"content":{"rendered":"<div><\/div>\n<div id=\"contenidoSUBTITULO\" class=\" contenidoSubTitulo\">\n<p><span id=\"contenidoSUBTITULO-colL0-DB:1\" class=\"contenidoTituloSubtitulo\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-111 size-full\" src=\"http:\/\/palenquerobledal.com\/web\/wp-content\/uploads\/2017\/08\/PILDORAS-PARA-VEHICULO2.png\" alt=\"\" width=\"1349\" height=\"500\" srcset=\"https:\/\/palenquerobledal.com\/web\/wp-content\/uploads\/2017\/08\/PILDORAS-PARA-VEHICULO2.png 1349w, https:\/\/palenquerobledal.com\/web\/wp-content\/uploads\/2017\/08\/PILDORAS-PARA-VEHICULO2-300x111.png 300w, https:\/\/palenquerobledal.com\/web\/wp-content\/uploads\/2017\/08\/PILDORAS-PARA-VEHICULO2-768x285.png 768w, https:\/\/palenquerobledal.com\/web\/wp-content\/uploads\/2017\/08\/PILDORAS-PARA-VEHICULO2-1024x380.png 1024w\" sizes=\"(max-width: 1349px) 100vw, 1349px\" \/><\/span><\/p>\n<p><span id=\"contenidoSUBTITULO-colL0-DB:1\" class=\"contenidoTituloSubtitulo\">En muchas ocasiones debe uno ponerse en la piel de los dem\u00e1s para tratar de comprender lo que puede sentir.<\/span><\/p>\n<div class=\"figContainer imgWide\"><strong>Ceder o no ceder un asiento, esa es la cuesti\u00f3n.<\/strong><\/div>\n<\/div>\n<div id=\"contenidoContenido\" class=\" bContenidoContenido\">\n<p>La buena educaci\u00f3n ense\u00f1a a ceder un asiento siempre que sea posible. No es una cuesti\u00f3n de moda sino\u00a0<strong>un gesto de atenci\u00f3n y cortes\u00eda<\/strong>\u00a0hacia otra persona. Ceder un asuento es una regla general que contempla cualquier libro de urbanidad, buenas maneras o manual de contenido similar. Es una norma de car\u00e1cter casi universal:\u00a0<strong>ceder el asiento a las personas mayores, mujeres<\/strong>\u00a0y personas con dificultades o alguna discapacidad o minusval\u00eda.<\/p>\n<p>Pero, \u00bfqu\u00e9 ocurre realmente en el d\u00eda a d\u00eda ? La ajetreada vida en las grandes ciudades, las prisas, las aglomeraciones, etc. han dado lugar al \u00ab<strong>olvido\u00bb de muchos buenos gestos de cortes\u00eda para con los dem\u00e1s<\/strong>. Entre ellos, est\u00e1 el de ceder un asiento. Un buen asiento se ha convertido en una \u00abpropiedad\u00bb que nadie quiere ceder.<\/p>\n<p>Da mucha pena e, incluso coraje, ver a un jovencito o jovencita, o bien a personas de mediana edad,\u00a0<strong>sentados en el autob\u00fas, en el tren, en el metro<\/strong>, o en otros medios de transporte, mientras una se\u00f1ora mayor, una mujer embarazada o bien un se\u00f1or mayor con grandes dificultades para caminar permanece en pie durante un trayecto. \u00bfQu\u00e9 educaci\u00f3n han recibido? Si hay que aclarar que no todo el mundo es as\u00ed, por suerte.\u00a0<strong>Tambi\u00e9n hay j\u00f3venes y personas de todas las edades\u00a0muy bien educadas<\/strong>.<\/p>\n<div class=\"PunteadoRIGHT\">\n<p>\u00abNo hay excusas para la falta de educaci\u00f3n\u00bb<\/p>\n<\/div>\n<h3><strong>\u00bfHan cambiado los tiempos?<\/strong><\/h3>\n<p>Si, claro que han cambiado. Pero\u00a0<strong>las personas siguen siendo las mismas<\/strong>, y no deben perder las buenas costumbres. \u00bfQu\u00e9 le parecer\u00eda a uno de estos j\u00f3venes que fuera su madre con un beb\u00e9 en sus brazos, su abuela o abuelo,\u00a0los que permanecieran en pie en un transporte p\u00fablico mientras un jovencito est\u00e1 c\u00f3modamente sentado escuchando m\u00fasca, leyendo o simplemente mirando a los dem\u00e1s pasajeros?\u00a0<strong>No hay excusas<\/strong>. Aislarse coloc\u00e1ndose unos auriculares o mirando el tel\u00e9fono m\u00f3vil\/celular para ignorar lo que ocurre a su alrededor no es una excusa. Vivimos en el mundo real y como tal hay que saber convivir con los dem\u00e1s. No se puede mirar a otro lado para ignorar estas situaciones.<\/p>\n<p>Hay ocasiones en la que\u00a0<strong>uno debe ponerse en la piel de los dem\u00e1s para tratar de comprender lo que puede sentir<\/strong>.\u00a0Si Dios quiere, todos llegaremos a ser personas mayores o con alg\u00fan tipo de problema de movilidad, y tendremos las mismas necesidades que hoy tienen las personas a las que ignoramos.<\/p>\n<p><ins class=\"adsbygoogle\" data-ad-format=\"fluid\" data-ad-layout=\"in-article\" data-ad-client=\"ca-pub-3922852115054734\" data-ad-slot=\"7232817492\" data-adsbygoogle-status=\"done\"><ins id=\"aswift_3_expand\"><ins id=\"aswift_3_anchor\"><\/ins><\/ins><\/ins>Ceder un asiento es un gesto de cortes\u00eda, un gesto de generosidad;\u00a0<strong>no cuesta nada y hace que la convivencia sea m\u00e1s grata, cordial y agradable<\/strong>. Desde luego, no se puede obligar a nadie a tener este tipo de gestos, pero la educaci\u00f3n deber\u00eda ense\u00f1ar a tenerlos de forma espont\u00e1nea. Tomamos de una campa\u00f1a publicitaria, de hace muchos a\u00f1os, una frase que puede servirnos para todo lo expresado en este art\u00edculo, y v\u00e1lido, para otras muchas ocasiones:\u00a0<strong>\u00abHoy por ti&#8230; y ma\u00f1ana por mi\u00bb<\/strong>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En muchas ocasiones debe uno ponerse en la piel de los dem\u00e1s para tratar de comprender lo que puede sentir. Ceder o no ceder un asiento, esa es la cuesti\u00f3n. La buena educaci\u00f3n ense\u00f1a a ceder un asiento siempre que sea posible. No es una cuesti\u00f3n de moda sino\u00a0un gesto de atenci\u00f3n y cortes\u00eda\u00a0hacia otra&hellip;<\/p>\n<p class=\"more-link\"><a href=\"https:\/\/palenquerobledal.com\/web\/2017\/08\/18\/ceder-el-asiento-una-cuestion-de-educacion\/\" class=\"themebutton2\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":113,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/posts\/110"}],"collection":[{"href":"https:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":2,"href":"https:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/posts\/110\/revisions"}],"predecessor-version":[{"id":114,"href":"https:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/posts\/110\/revisions\/114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/media\/113"}],"wp:attachment":[{"href":"https:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/media?parent=110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/categories?post=110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/tags?post=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}