{"id":50,"date":"2017-08-01T23:10:53","date_gmt":"2017-08-01T23:10:53","guid":{"rendered":"http:\/\/palenquerobledal.com\/web\/?p=50"},"modified":"2021-11-04T03:12:44","modified_gmt":"2021-11-04T03:12:44","slug":"un-transporte-eficiente-mejora-la-calidad-del-medio-ambiente","status":"publish","type":"post","link":"http:\/\/palenquerobledal.com\/web\/2017\/08\/01\/un-transporte-eficiente-mejora-la-calidad-del-medio-ambiente\/","title":{"rendered":"Un transporte eficiente mejora la calidad del medio ambiente"},"content":{"rendered":"<div class=\"panel-grid\" id=\"pg-50-0\"><div class=\"panel-grid-core\"><div class=\"panel-grid-cell\" id=\"pgc-50-0-0\"><div class=\"panel-widget-style\"><p>En Colombia se est\u00e1n implementando acciones que a futuro permitir\u00e1n una mayor eficiencia energ\u00e9tica.<\/p><\/div><\/div><\/div><\/div><p>&hellip;<p class=\"more-link\"><a href=\"http:\/\/palenquerobledal.com\/web\/2017\/08\/01\/un-transporte-eficiente-mejora-la-calidad-del-medio-ambiente\/\" class=\"themebutton2\">Read More<\/a><\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>En Colombia se est\u00e1n implementando acciones que a futuro permitir\u00e1n una mayor eficiencia energ\u00e9tica.&hellip;Read More<\/p>\n","protected":false},"author":1,"featured_media":52,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/posts\/50"}],"collection":[{"href":"http:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/comments?post=50"}],"version-history":[{"count":1,"href":"http:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/posts\/50\/revisions"}],"predecessor-version":[{"id":51,"href":"http:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/posts\/50\/revisions\/51"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/media\/52"}],"wp:attachment":[{"href":"http:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/media?parent=50"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/categories?post=50"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/palenquerobledal.com\/web\/wp-json\/wp\/v2\/tags?post=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}